{"id":30647,"date":"2020-04-25T18:23:52","date_gmt":"2020-04-25T15:23:52","guid":{"rendered":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid.jpg"},"modified":"2020-04-25T18:23:52","modified_gmt":"2020-04-25T15:23:52","slug":"femeie-deces-covid-2","status":"inherit","type":"attachment","link":"https:\/\/www.elenarobu.md\/fr\/femeie-deces-covid-2\/","title":{"rendered":"femeie deces covid"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-30647","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>femeie deces covid - ER News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid.jpg\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"femeie deces covid - ER News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid.jpg\" \/>\n<meta property=\"og:site_name\" content=\"ER News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elenarobublog\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"635\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elenarobu.md\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/femeie-deces-covid.jpg\",\"url\":\"https:\\\/\\\/www.elenarobu.md\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/femeie-deces-covid.jpg\",\"name\":\"femeie deces covid - ER News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elenarobu.md\\\/fr\\\/#website\"},\"datePublished\":\"2020-04-25T15:23:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elenarobu.md\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/femeie-deces-covid.jpg#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.elenarobu.md\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/femeie-deces-covid.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elenarobu.md\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/femeie-deces-covid.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/www.elenarobu.md\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"femeie deces covid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elenarobu.md\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.elenarobu.md\\\/fr\\\/\",\"name\":\"ER News\",\"description\":\"Mes Informations L'information est le pouvoir! \\r\\nVotre pouvoir est votre source!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.elenarobu.md\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.elenarobu.md\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.elenarobu.md\\\/fr\\\/#organization\",\"name\":\"ER News - Primul Portal de \u015etiri din Diaspora\",\"url\":\"https:\\\/\\\/www.elenarobu.md\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.elenarobu.md\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.elenarobu.md\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Favicon-ER-News.png\",\"contentUrl\":\"https:\\\/\\\/www.elenarobu.md\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Favicon-ER-News.png\",\"width\":512,\"height\":512,\"caption\":\"ER News - Primul Portal de \u015etiri din Diaspora\"},\"image\":{\"@id\":\"https:\\\/\\\/www.elenarobu.md\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/elenarobublog\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"femeie deces covid - ER News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid.jpg","og_locale":"fr_FR","og_type":"article","og_title":"femeie deces covid - ER News","og_url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid.jpg","og_site_name":"ER News","article_publisher":"https:\/\/www.facebook.com\/elenarobublog\/","og_image":[{"width":960,"height":635,"url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid.jpg","url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid.jpg","name":"femeie deces covid - ER News","isPartOf":{"@id":"https:\/\/www.elenarobu.md\/fr\/#website"},"datePublished":"2020-04-25T15:23:52+00:00","breadcrumb":{"@id":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid.jpg#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/www.elenarobu.md\/fr\/"},{"@type":"ListItem","position":2,"name":"femeie deces covid"}]},{"@type":"WebSite","@id":"https:\/\/www.elenarobu.md\/fr\/#website","url":"https:\/\/www.elenarobu.md\/fr\/","name":"ER News","description":"Mes Informations L'information est le pouvoir! \r\nVotre pouvoir est votre source!","publisher":{"@id":"https:\/\/www.elenarobu.md\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elenarobu.md\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.elenarobu.md\/fr\/#organization","name":"ER News - Primul Portal de \u015etiri din Diaspora","url":"https:\/\/www.elenarobu.md\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elenarobu.md\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2019\/03\/Favicon-ER-News.png","contentUrl":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2019\/03\/Favicon-ER-News.png","width":512,"height":512,"caption":"ER News - Primul Portal de \u015etiri din Diaspora"},"image":{"@id":"https:\/\/www.elenarobu.md\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elenarobublog\/"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"198\" src=\"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid-300x198.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid-300x198.jpg 300w, https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid-768x508.jpg 768w, https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":635,"file":"2020\/04\/femeie-deces-covid.jpg","sizes":{"medium":{"file":"femeie-deces-covid-300x198.jpg","width":300,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid-300x198.jpg"},"thumbnail":{"file":"femeie-deces-covid-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid-150x150.jpg"},"medium_large":{"file":"femeie-deces-covid-768x508.jpg","width":768,"height":508,"mime_type":"image\/jpeg","source_url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid-768x508.jpg"},"better-amp-small":{"file":"femeie-deces-covid-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid-100x100.jpg"},"better-amp-normal":{"file":"femeie-deces-covid-260x200.jpg","width":260,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid-260x200.jpg"},"better-amp-large":{"file":"femeie-deces-covid-450x300.jpg","width":450,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid-450x300.jpg"},"publisher-tb1":{"file":"femeie-deces-covid-86x64.jpg","width":86,"height":64,"mime_type":"image\/jpeg","source_url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid-86x64.jpg"},"publisher-sm":{"file":"femeie-deces-covid-210x136.jpg","width":210,"height":136,"mime_type":"image\/jpeg","source_url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid-210x136.jpg"},"publisher-mg2":{"file":"femeie-deces-covid-279x220.jpg","width":279,"height":220,"mime_type":"image\/jpeg","source_url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid-279x220.jpg"},"publisher-md":{"file":"femeie-deces-covid-357x210.jpg","width":357,"height":210,"mime_type":"image\/jpeg","source_url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid-357x210.jpg"},"publisher-lg":{"file":"femeie-deces-covid-750x430.jpg","width":750,"height":430,"mime_type":"image\/jpeg","source_url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid-750x430.jpg"},"publisher-full":{"file":"femeie-deces-covid-960x580.jpg","width":960,"height":580,"mime_type":"image\/jpeg","source_url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid-960x580.jpg"},"publisher-tall-sm":{"file":"femeie-deces-covid-180x217.jpg","width":180,"height":217,"mime_type":"image\/jpeg","source_url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid-180x217.jpg"},"publisher-tall-lg":{"file":"femeie-deces-covid-267x322.jpg","width":267,"height":322,"mime_type":"image\/jpeg","source_url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid-267x322.jpg"},"publisher-tall-big":{"file":"femeie-deces-covid-368x445.jpg","width":368,"height":445,"mime_type":"image\/jpeg","source_url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid-368x445.jpg"},"full":{"file":"femeie-deces-covid.jpg","width":960,"height":635,"mime_type":"image\/jpeg","source_url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.elenarobu.md\/wp-content\/uploads\/2020\/04\/femeie-deces-covid.jpg","_links":{"self":[{"href":"https:\/\/www.elenarobu.md\/fr\/wp-json\/wp\/v2\/media\/30647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elenarobu.md\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.elenarobu.md\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.elenarobu.md\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elenarobu.md\/fr\/wp-json\/wp\/v2\/comments?post=30647"}]}}